{"id":108223,"date":"2021-08-17T04:00:20","date_gmt":"2021-08-17T02:00:20","guid":{"rendered":"https:\/\/akomokids.com\/product\/maileg-wellness-set-2\/"},"modified":"2026-06-08T07:49:25","modified_gmt":"2026-06-08T05:49:25","slug":"maileg-wellness-set","status":"publish","type":"product","link":"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/","title":{"rendered":"Maileg &#8211; Wellness Set"},"content":{"rendered":"<h2>Maileg Wellness Set, Badezeit!<\/h2>\n<p>Das Wellness-Set wird mit einem Handtuch, einer Badem\u00fctze und einem Badehandschuh geliefert. Die M\u00fctze und der Handschuh passen zu den Maileg Hasen Gr\u00f6\u00dfe 1 &amp; 2 und zur Teddy Familie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maileg Wellness Set, Badezeit! Das Wellness-Set wird mit einem Handtuch, einer Badem\u00fctze und einem Badehandschuh geliefert. Die M\u00fctze und der Handschuh passen zu den Maileg Hasen Gr\u00f6\u00dfe 1 &amp; 2 und zur Teddy Familie.<\/p>\n","protected":false},"featured_media":1000000137833,"template":"","meta":{"_acf_changed":false},"product_brand":[2073,2163],"product_cat":[4077,4361,4290],"product_tag":[],"class_list":["post-108223","product","type-product","status-publish","has-post-thumbnail","product_brand-maileg","product_brand-maileg-de","product_cat-maileg-toys","product_cat-maileg-spielen","product_cat-spielen","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"outofstock","bundle_stock_quantity":0,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"exclude_global_add_ons":[],"addons":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Maileg | Wellness Set | Sofort Lieferbar<\/title>\n<meta name=\"description\" content=\"Maileg Kollektion online | Puppenhausm\u00f6bel und Maileg Zubeh\u00f6r | M\u00e4use in Streichholzschachtel von Maileg | Schnelle Lieferung!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maileg - Wellness Set\" \/>\n<meta property=\"og:description\" content=\"Maileg Kollektion online | Puppenhausm\u00f6bel und Maileg Zubeh\u00f6r | M\u00e4use in Streichholzschachtel von Maileg | Schnelle Lieferung!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/\" \/>\n<meta property=\"og:site_name\" content=\"Akomo Kids\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/akomokids\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T05:49:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;&nbsp;11,70\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"ausverkauft\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/maileg-wellness-set\\\/\",\"url\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/maileg-wellness-set\\\/\",\"name\":\"Maileg | Wellness Set | Sofort Lieferbar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/maileg-wellness-set\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/maileg-wellness-set\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/akomokids.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/maileg-wellness-set-11-0305-00.jpg\",\"datePublished\":\"2021-08-17T02:00:20+00:00\",\"dateModified\":\"2026-06-08T05:49:25+00:00\",\"description\":\"Maileg Kollektion online | Puppenhausm\u00f6bel und Maileg Zubeh\u00f6r | M\u00e4use in Streichholzschachtel von Maileg | Schnelle Lieferung!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/maileg-wellness-set\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/maileg-wellness-set\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/maileg-wellness-set\\\/#primaryimage\",\"url\":\"https:\\\/\\\/akomokids.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/maileg-wellness-set-11-0305-00.jpg\",\"contentUrl\":\"https:\\\/\\\/akomokids.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/maileg-wellness-set-11-0305-00.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/maileg-wellness-set\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/akomokids.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/akomokids.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maileg &#8211; Wellness Set\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/akomokids.com\\\/de\\\/\",\"name\":\"Akomo Kids\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/akomokids.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/#organization\",\"name\":\"Akomo Kids | Design Furniture & Lifestyle\",\"alternateName\":\"Akomo Kids | family concept store\",\"url\":\"https:\\\/\\\/akomokids.com\\\/de\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/maileg-wellness-set\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/maileg-wellness-set\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/akomokids\\\/\",\"https:\\\/\\\/www.instagram.com\\\/akomokids\\\/\"],\"description\":\"Shop premium baby and kids products at Akomo Kids\",\"legalName\":\"Akomo Kids\",\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/maileg-wellness-set\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/akomokids.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/02\\\/Akomo-Logo-uil.jpg\",\"contentUrl\":\"https:\\\/\\\/akomokids.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/02\\\/Akomo-Logo-uil.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Akomo Kids | Design Furniture & Lifestyle\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"11.70\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"11-0305-00\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Maileg | Wellness Set | Sofort Lieferbar","description":"Maileg Kollektion online | Puppenhausm\u00f6bel und Maileg Zubeh\u00f6r | M\u00e4use in Streichholzschachtel von Maileg | Schnelle Lieferung!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/","og_locale":"de_DE","og_type":"article","og_title":"Maileg - Wellness Set","og_description":"Maileg Kollektion online | Puppenhausm\u00f6bel und Maileg Zubeh\u00f6r | M\u00e4use in Streichholzschachtel von Maileg | Schnelle Lieferung!","og_url":"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/","og_site_name":"Akomo Kids","article_publisher":"https:\/\/www.facebook.com\/akomokids\/","article_modified_time":"2026-06-08T05:49:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Preis":"&euro;&nbsp;11,70","Verf\u00fcgbarkeit":"ausverkauft"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/","url":"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/","name":"Maileg | Wellness Set | Sofort Lieferbar","isPartOf":{"@id":"https:\/\/akomokids.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/#primaryimage"},"image":{"@id":"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/#primaryimage"},"thumbnailUrl":"https:\/\/akomokids.com\/wp-content\/uploads\/2025\/06\/maileg-wellness-set-11-0305-00.jpg","datePublished":"2021-08-17T02:00:20+00:00","dateModified":"2026-06-08T05:49:25+00:00","description":"Maileg Kollektion online | Puppenhausm\u00f6bel und Maileg Zubeh\u00f6r | M\u00e4use in Streichholzschachtel von Maileg | Schnelle Lieferung!","breadcrumb":{"@id":"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/#primaryimage","url":"https:\/\/akomokids.com\/wp-content\/uploads\/2025\/06\/maileg-wellness-set-11-0305-00.jpg","contentUrl":"https:\/\/akomokids.com\/wp-content\/uploads\/2025\/06\/maileg-wellness-set-11-0305-00.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/akomokids.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/akomokids.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Maileg &#8211; Wellness Set"}]},{"@type":"WebSite","@id":"https:\/\/akomokids.com\/de\/#website","url":"https:\/\/akomokids.com\/de\/","name":"Akomo Kids","description":"","publisher":{"@id":"https:\/\/akomokids.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/akomokids.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","Place"],"@id":"https:\/\/akomokids.com\/de\/#organization","name":"Akomo Kids | Design Furniture & Lifestyle","alternateName":"Akomo Kids | family concept store","url":"https:\/\/akomokids.com\/de\/","logo":{"@id":"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/#local-main-organization-logo"},"image":{"@id":"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/akomokids\/","https:\/\/www.instagram.com\/akomokids\/"],"description":"Shop premium baby and kids products at Akomo Kids","legalName":"Akomo Kids","telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/akomokids.com\/de\/product\/maileg-wellness-set\/#local-main-organization-logo","url":"https:\/\/akomokids.com\/wp-content\/uploads\/sites\/4\/2026\/02\/Akomo-Logo-uil.jpg","contentUrl":"https:\/\/akomokids.com\/wp-content\/uploads\/sites\/4\/2026\/02\/Akomo-Logo-uil.jpg","width":1000,"height":1000,"caption":"Akomo Kids | Design Furniture & Lifestyle"}]},"product_price_amount":"11.70","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"11-0305-00","product_condition":"new"},"acf":{"google_lifestyle_image":null},"_links":{"self":[{"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product\/108223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/media?parent=108223"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product_brand?post=108223"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product_cat?post=108223"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product_tag?post=108223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}