{"id":107912,"date":"2022-03-03T15:35:00","date_gmt":"2022-03-03T14:35:00","guid":{"rendered":"https:\/\/akomokids.com\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/"},"modified":"2026-03-14T14:28:05","modified_gmt":"2026-03-14T13:28:05","slug":"kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche","status":"publish","type":"product","link":"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/","title":{"rendered":"KAS Kopenhagen &#8211; Eli Combi Junior Bett &#8211; Ger\u00e4ucherte Eiche &#8211; 90 x 160 cm"},"content":{"rendered":"<h2>KAS Kopenhagen, nachhaltige Designerm\u00f6bel<\/h2>\n<p>Die Leidenschaft f\u00fcr nordisches Design hat Kasandra, die Gr\u00fcnderin von KAS Kopenhagen, dazu motiviert wundersch\u00f6ne M\u00f6bel f\u00fcr ihre Kinder zu kreieren. Der Mix aus ausdrucksstarken modernen Formen mit schlichtem Design macht die Designerm\u00f6bel sowohl f\u00fcr Kinder als auch f\u00fcr Erwachsene attraktiv. Alle M\u00f6bel werden aus FSC-zertifiziertem Holz aus FSC-zertifizierten W\u00e4ldern hergestellt und es werden nur schadstorfffrdie Farben verwendet.<\/p>\n<h3>KAS Kopenhagen Eli Kollektion &#8211; konvertierbar<\/h3>\n<p>Die Eli Kollektion besteht aus massiver Eiche und kann in mehrere verschiedene Betten umgewandelt werden. So kannst du zum Beispiel mit der Junior Version anfangen und das Bett beim Wachstum deines Kindes auf 90x200cm erweitern. Dar\u00fcberhinaus k\u00f6nnen die Enden des Bettes entfernt werden, so dass das Eli Bett auch zum Combi oder Daybed umgewandelt werden kann. Auch ein Sicherheitsset ist erh\u00e4ltlich, so dass dein Kind nicht aus dem Bett rollen kann. Alle Umwandlungsset k\u00f6nnen bei uns erworben werden. Wir beraten gerne!<br \/>\n<a href=\"https:\/\/akomokids.com\/wp-content\/uploads\/2022\/03\/Eli-Bed-4.jpg\"><img decoding=\"async\" class=\"wp-image-108762 aligncenter lazyload\" data-src=\"https:\/\/akomokids.com\/wp-content\/uploads\/2022\/03\/Eli-Bed-4-300x300.jpg\" alt=\"\" width=\"327\" height=\"327\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 327px; --smush-placeholder-aspect-ratio: 327\/327;\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schenke deinem Kind einen ruhigen und vertrauten Ort zum Schlafen und Entspannen. Dieses Massivholz-Bett aus Eiche ist ein echter Allesk\u00f6nner: Du kannst das Kopfteil ganz einfach abnehmen und es in ein Daybed verwandeln \u2013 und das Bett zudem verl\u00e4ngern, wenn dein Kind gr\u00f6\u00dfer wird. So begleitet es euch noch l\u00e4nger und bietet jahrelangen Halt. Ma\u00dfe: 174 \u00d7 94 \u00d7 72 cm. Mit dem Conversion Kit zum Eli Adult Bed umbaubar.<\/p>\n","protected":false},"featured_media":1000000140095,"template":"","meta":{"_acf_changed":false},"product_brand":[2143],"product_cat":[4339,4288,4287,4285],"product_tag":[],"class_list":["post-107912","product","type-product","status-publish","has-post-thumbnail","product_brand-kas-kopenhagen-de","product_cat-juniorbetten","product_cat-kinder-juniorbetten","product_cat-moebel","product_cat-wohnen","product_shipping_class-pallet-shipment","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"onbackorder","bundle_stock_quantity":0,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[97669,110454,97665,107314,107916,107687,113243],"exclude_global_add_ons":[],"addons":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>KAS Kopenhagen - Eli Combi Junior Bett - Ger\u00e4ucherte Eiche<\/title>\n<meta name=\"description\" content=\"KAS Kopenhagen - Designm\u00f6bel f\u00fcr dein Kinderzimmer &amp; Jugendzimmer! Hohe Qualit\u00e4t kombiniert mit sch\u00f6nem Design! Schnelle Lieferung!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KAS Kopenhagen - Eli Combi Junior Bett - Ger\u00e4ucherte Eiche - 90 x 160 cm\" \/>\n<meta property=\"og:description\" content=\"KAS Kopenhagen - Designm\u00f6bel f\u00fcr dein Kinderzimmer &amp; Jugendzimmer! Hohe Qualit\u00e4t kombiniert mit sch\u00f6nem Design! Schnelle Lieferung!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/\" \/>\n<meta property=\"og:site_name\" content=\"Akomo Kids\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/akomokids\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T13:28:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;&nbsp;686,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"bei Nachbestellung\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\\\/\",\"url\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\\\/\",\"name\":\"KAS Kopenhagen - Eli Combi Junior Bett - Ger\u00e4ucherte Eiche\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/akomokids.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/012357-8.jpg\",\"datePublished\":\"2022-03-03T14:35:00+00:00\",\"dateModified\":\"2026-03-14T13:28:05+00:00\",\"description\":\"KAS Kopenhagen - Designm\u00f6bel f\u00fcr dein Kinderzimmer & Jugendzimmer! Hohe Qualit\u00e4t kombiniert mit sch\u00f6nem Design! Schnelle Lieferung!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/akomokids.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/012357-8.jpg\",\"contentUrl\":\"https:\\\/\\\/akomokids.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/012357-8.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/akomokids.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/akomokids.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"KAS Kopenhagen &#8211; Eli Combi Junior Bett &#8211; Ger\u00e4ucherte Eiche &#8211; 90 x 160 cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/akomokids.com\\\/de\\\/\",\"name\":\"Akomo Kids\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/akomokids.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/#organization\",\"name\":\"Akomo Kids | Design Furniture & Lifestyle\",\"alternateName\":\"Akomo Kids | family concept store\",\"url\":\"https:\\\/\\\/akomokids.com\\\/de\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/akomokids\\\/\",\"https:\\\/\\\/www.instagram.com\\\/akomokids\\\/\"],\"description\":\"Shop premium baby and kids products at Akomo Kids\",\"legalName\":\"Akomo Kids\",\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/akomokids.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/02\\\/Akomo-Logo-uil.jpg\",\"contentUrl\":\"https:\\\/\\\/akomokids.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/02\\\/Akomo-Logo-uil.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Akomo Kids | Design Furniture & Lifestyle\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"686.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"Eli-combi22S\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"KAS Kopenhagen - Eli Combi Junior Bett - Ger\u00e4ucherte Eiche","description":"KAS Kopenhagen - Designm\u00f6bel f\u00fcr dein Kinderzimmer & Jugendzimmer! Hohe Qualit\u00e4t kombiniert mit sch\u00f6nem Design! Schnelle Lieferung!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/","og_locale":"de_DE","og_type":"article","og_title":"KAS Kopenhagen - Eli Combi Junior Bett - Ger\u00e4ucherte Eiche - 90 x 160 cm","og_description":"KAS Kopenhagen - Designm\u00f6bel f\u00fcr dein Kinderzimmer & Jugendzimmer! Hohe Qualit\u00e4t kombiniert mit sch\u00f6nem Design! Schnelle Lieferung!","og_url":"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/","og_site_name":"Akomo Kids","article_publisher":"https:\/\/www.facebook.com\/akomokids\/","article_modified_time":"2026-03-14T13:28:05+00:00","twitter_card":"summary_large_image","twitter_misc":{"Preis":"&euro;&nbsp;686,00","Verf\u00fcgbarkeit":"bei Nachbestellung"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/","url":"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/","name":"KAS Kopenhagen - Eli Combi Junior Bett - Ger\u00e4ucherte Eiche","isPartOf":{"@id":"https:\/\/akomokids.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/#primaryimage"},"image":{"@id":"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/#primaryimage"},"thumbnailUrl":"https:\/\/akomokids.com\/wp-content\/uploads\/2025\/06\/012357-8.jpg","datePublished":"2022-03-03T14:35:00+00:00","dateModified":"2026-03-14T13:28:05+00:00","description":"KAS Kopenhagen - Designm\u00f6bel f\u00fcr dein Kinderzimmer & Jugendzimmer! Hohe Qualit\u00e4t kombiniert mit sch\u00f6nem Design! Schnelle Lieferung!","breadcrumb":{"@id":"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/#primaryimage","url":"https:\/\/akomokids.com\/wp-content\/uploads\/2025\/06\/012357-8.jpg","contentUrl":"https:\/\/akomokids.com\/wp-content\/uploads\/2025\/06\/012357-8.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/akomokids.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/akomokids.com\/shop\/"},{"@type":"ListItem","position":3,"name":"KAS Kopenhagen &#8211; Eli Combi Junior Bett &#8211; Ger\u00e4ucherte Eiche &#8211; 90 x 160 cm"}]},{"@type":"WebSite","@id":"https:\/\/akomokids.com\/de\/#website","url":"https:\/\/akomokids.com\/de\/","name":"Akomo Kids","description":"","publisher":{"@id":"https:\/\/akomokids.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/akomokids.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","Place"],"@id":"https:\/\/akomokids.com\/de\/#organization","name":"Akomo Kids | Design Furniture & Lifestyle","alternateName":"Akomo Kids | family concept store","url":"https:\/\/akomokids.com\/de\/","logo":{"@id":"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/#local-main-organization-logo"},"image":{"@id":"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/akomokids\/","https:\/\/www.instagram.com\/akomokids\/"],"description":"Shop premium baby and kids products at Akomo Kids","legalName":"Akomo Kids","telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/akomokids.com\/de\/product\/kas-kopenhagen-eli-combi-junior-bett-geraucherte-eiche\/#local-main-organization-logo","url":"https:\/\/akomokids.com\/wp-content\/uploads\/sites\/4\/2026\/02\/Akomo-Logo-uil.jpg","contentUrl":"https:\/\/akomokids.com\/wp-content\/uploads\/sites\/4\/2026\/02\/Akomo-Logo-uil.jpg","width":1000,"height":1000,"caption":"Akomo Kids | Design Furniture & Lifestyle"}]},"product_price_amount":"686.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"Eli-combi22S","product_condition":"new"},"acf":{"google_lifestyle_image":null},"_links":{"self":[{"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product\/107912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/media?parent=107912"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product_brand?post=107912"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product_cat?post=107912"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product_tag?post=107912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}