{"id":107246,"date":"2023-12-11T15:22:22","date_gmt":"2023-12-11T14:22:22","guid":{"rendered":"https:\/\/akomokids.com\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/"},"modified":"2025-06-13T11:20:24","modified_gmt":"2025-06-13T09:20:24","slug":"little-lights-kinder-nachtlicht-lowe-serengeti-wald","status":"publish","type":"product","link":"https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/","title":{"rendered":"Little Lights &#8211; Kinder Nachtlicht &#8211; L\u00f6we &#8211; Serengeti Wald"},"content":{"rendered":"<h2>Little Lights &#8211; Nachtlichter &amp; Nachttischlampen<\/h2>\n<p>Lerne die tolle Marke Little Lights kennen! Wo vorher langweilige Kinderzimmer Nachtleuchten standen, k\u00f6nnen endlich Designerst\u00fccke das Babyzimmer oder Kinderzimmer erhellen. Eine Kollektion, die aus s\u00fc\u00dfen Schlaftieren, coolen Fahrzeugen und zauberhaften Regenb\u00f6gen besteht und f\u00fcr eine unvergessliche Atmosph\u00e4re sorgt. Jede Kinderzimmer Lampe wird mit gro\u00dfer Sorgfalt im Familienbetrieb in Polen hergestellt und handgefertigt. Somit ist jede Kinder Nachttischlampe ein Unikat.<\/p>\n<h3>Spielen, schlafen &amp; tr\u00e4umen<\/h3>\n<p>Neben der gem\u00fctlichen Atmosph\u00e4re im Babyzimmer oder Kinderzimmer sorgen die wundersch\u00f6nen aber auch lustigen Lampen von Little Lights auch daf\u00fcr, dass dein Kind einen schlafend Freund neben sich hat, welcher leuchtet und im Dunkeln einen Besch\u00fctzer darstellt. Da die Lampen \u00fcber einen Dimmer verf\u00fcgen, sind diese ideal um Gutenachtgeschichten vorzulesen oder aber Nachts beim Stillen eine gem\u00fctliches Licht zu schaffen. Mit dem Timer kann eingestellt werden, ob das Licht nach 30, 60 oder 90 Minuten erlischt. Schl\u00e4ft dein Kind am liebsten die ganze Nacht bei Licht? Dank der LED-Technologie ist dies auch sicher und dein Kind braucht keine Angst mehr zu haben.<\/p>\n<p>Ein wunderbares Produkt, das die ganze Familie jahrelang begleitet.<\/p>\n<h3>Details im \u00dcberblick<\/h3>\n<ul>\n<li>Ma\u00dfe: 37 x 19 x 5,5 cm<\/li>\n<li>Material: massives Kiefernholz<\/li>\n<li>Fernbedienung mit Power-Taste, Dimmer &amp; Timer<\/li>\n<li>Kabell\u00e4nge: 180 cm<\/li>\n<li>Kann an die Wand geh\u00e4ngt werden<\/li>\n<li>LED-Leuchten \/ Warmwei\u00df 2,2W<\/li>\n<li>Eingang: AC 100-240 Ausgang: DC 24V<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Little Lights &#8211; Nachtlichter &amp; Nachttischlampen Lerne die tolle Marke Little Lights kennen! Wo vorher langweilige Kinderzimmer Nachtleuchten standen, k\u00f6nnen endlich Designerst\u00fccke das Babyzimmer oder Kinderzimmer erhellen. Eine Kollektion, die aus s\u00fc\u00dfen Schlaftieren, coolen Fahrzeugen und zauberhaften Regenb\u00f6gen besteht und f\u00fcr eine unvergessliche Atmosph\u00e4re sorgt. Jede Kinderzimmer Lampe wird mit gro\u00dfer Sorgfalt im Familienbetrieb in &hellip; <a href=\"https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/\">Continued<\/a><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[2159],"product_cat":[4307,4359,4285],"product_tag":[],"class_list":["post-107246","product","type-product","status-publish","product_brand-little-lights-de","product_cat-dekoration","product_cat-lampen-wohnen","product_cat-wohnen","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"onbackorder","bundle_stock_quantity":0,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"exclude_global_add_ons":[],"addons":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Little Lights | L\u00f6we - Serengeti Wald | Gratis Versand!<\/title>\n<meta name=\"description\" content=\"Little Lights Kinder Nachttischlampen &amp; Babyzimmer\/Kinderzimmer Nachtlichter in den coolsten Designs! Entdecke das gesamte Sortiment bei Akomo Kids!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Little Lights - Kinder Nachtlicht - L\u00f6we - Serengeti Wald\" \/>\n<meta property=\"og:description\" content=\"Little Lights Kinder Nachttischlampen &amp; Babyzimmer\/Kinderzimmer Nachtlichter in den coolsten Designs! Entdecke das gesamte Sortiment bei Akomo Kids!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/\" \/>\n<meta property=\"og:site_name\" content=\"Akomo Kids\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/akomokids\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-13T09:20:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;&nbsp;209,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"bei Nachbestellung\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\\\/\",\"url\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\\\/\",\"name\":\"Little Lights | L\u00f6we - Serengeti Wald | Gratis Versand!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/#website\"},\"datePublished\":\"2023-12-11T14:22:22+00:00\",\"dateModified\":\"2025-06-13T09:20:24+00:00\",\"description\":\"Little Lights Kinder Nachttischlampen & Babyzimmer\\\/Kinderzimmer Nachtlichter in den coolsten Designs! Entdecke das gesamte Sortiment bei Akomo Kids!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/akomokids.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/akomokids.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Little Lights &#8211; Kinder Nachtlicht &#8211; L\u00f6we &#8211; Serengeti Wald\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/akomokids.com\\\/de\\\/\",\"name\":\"Akomo Kids\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/akomokids.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/#organization\",\"name\":\"Akomo Kids | Design Furniture & Lifestyle\",\"alternateName\":\"Akomo Kids | family concept store\",\"url\":\"https:\\\/\\\/akomokids.com\\\/de\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/akomokids\\\/\",\"https:\\\/\\\/www.instagram.com\\\/akomokids\\\/\"],\"description\":\"Shop premium baby and kids products at Akomo Kids\",\"legalName\":\"Akomo Kids\",\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/akomokids.com\\\/de\\\/product\\\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/akomokids.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/02\\\/Akomo-Logo-uil.jpg\",\"contentUrl\":\"https:\\\/\\\/akomokids.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/02\\\/Akomo-Logo-uil.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Akomo Kids | Design Furniture & Lifestyle\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"209.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LL044-470\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Little Lights | L\u00f6we - Serengeti Wald | Gratis Versand!","description":"Little Lights Kinder Nachttischlampen & Babyzimmer\/Kinderzimmer Nachtlichter in den coolsten Designs! Entdecke das gesamte Sortiment bei Akomo Kids!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/","og_locale":"de_DE","og_type":"article","og_title":"Little Lights - Kinder Nachtlicht - L\u00f6we - Serengeti Wald","og_description":"Little Lights Kinder Nachttischlampen & Babyzimmer\/Kinderzimmer Nachtlichter in den coolsten Designs! Entdecke das gesamte Sortiment bei Akomo Kids!","og_url":"https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/","og_site_name":"Akomo Kids","article_publisher":"https:\/\/www.facebook.com\/akomokids\/","article_modified_time":"2025-06-13T09:20:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Preis":"&euro;&nbsp;209,00","Verf\u00fcgbarkeit":"bei Nachbestellung"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/","url":"https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/","name":"Little Lights | L\u00f6we - Serengeti Wald | Gratis Versand!","isPartOf":{"@id":"https:\/\/akomokids.com\/de\/#website"},"datePublished":"2023-12-11T14:22:22+00:00","dateModified":"2025-06-13T09:20:24+00:00","description":"Little Lights Kinder Nachttischlampen & Babyzimmer\/Kinderzimmer Nachtlichter in den coolsten Designs! Entdecke das gesamte Sortiment bei Akomo Kids!","breadcrumb":{"@id":"https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/akomokids.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/akomokids.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Little Lights &#8211; Kinder Nachtlicht &#8211; L\u00f6we &#8211; Serengeti Wald"}]},{"@type":"WebSite","@id":"https:\/\/akomokids.com\/de\/#website","url":"https:\/\/akomokids.com\/de\/","name":"Akomo Kids","description":"","publisher":{"@id":"https:\/\/akomokids.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/akomokids.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","Place"],"@id":"https:\/\/akomokids.com\/de\/#organization","name":"Akomo Kids | Design Furniture & Lifestyle","alternateName":"Akomo Kids | family concept store","url":"https:\/\/akomokids.com\/de\/","logo":{"@id":"https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/#local-main-organization-logo"},"image":{"@id":"https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/akomokids\/","https:\/\/www.instagram.com\/akomokids\/"],"description":"Shop premium baby and kids products at Akomo Kids","legalName":"Akomo Kids","telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/akomokids.com\/de\/product\/little-lights-kinder-nachtlicht-lowe-serengeti-wald\/#local-main-organization-logo","url":"https:\/\/akomokids.com\/wp-content\/uploads\/sites\/4\/2026\/02\/Akomo-Logo-uil.jpg","contentUrl":"https:\/\/akomokids.com\/wp-content\/uploads\/sites\/4\/2026\/02\/Akomo-Logo-uil.jpg","width":1000,"height":1000,"caption":"Akomo Kids | Design Furniture & Lifestyle"}]},"product_price_amount":"209.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"LL044-470","product_condition":"new"},"acf":{"google_lifestyle_image":null},"_links":{"self":[{"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product\/107246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/media?parent=107246"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product_brand?post=107246"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product_cat?post=107246"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/akomokids.com\/de\/wp-json\/wp\/v2\/product_tag?post=107246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}